{"id":5681,"date":"2024-07-16T17:17:55","date_gmt":"2024-07-16T17:17:55","guid":{"rendered":"https:\/\/www.acfo-acaf.com\/?p=5681"},"modified":"2024-07-16T17:20:48","modified_gmt":"2024-07-16T17:20:48","slug":"assemblee-generale-extraordinaire-de-lacfo-acaf-le-6-aout-2024","status":"publish","type":"post","link":"https:\/\/www.acfo-acaf.com\/fr\/assemblee-generale-extraordinaire-de-lacfo-acaf-le-6-aout-2024\/","title":{"rendered":"Assembl\u00e9e g\u00e9n\u00e9rale extraordinaire de l\u2019ACFO-ACAF le 6\u00a0ao\u00fbt 2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Conform\u00e9ment \u00e0 <a href=\"https:\/\/bit.ly\/Reglement9121\" data-type=\"link\" data-id=\"https:\/\/bit.ly\/Reglement9121\">l\u2019article 9.12.1<\/a> du R\u00e8glement, le Conseil d\u2019administration de l\u2019ACFO-ACAF a convoqu\u00e9 une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire (AGE) qui aura lieu en ligne\u00a0<strong>le 6 ao\u00fbt 2024 \u00e0 18\u00a0h 00 HE.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le but de l\u2019AGE est de pr\u00e9senter une modification du R\u00e8glement. Les membres de l\u2019ACFO-ACAF trouveront tous les d\u00e9tails \u00e0 ce sujet en cliquant <a href=\"https:\/\/www.acfo-acaf.com\/wp-content\/uploads\/2024\/07\/2024-07-15-SGMResolutionFR.pdf\" data-type=\"link\" data-id=\"https:\/\/www.acfo-acaf.com\/wp-content\/uploads\/2024\/07\/2024-07-15-SGMResolutionFR.pdf\">sur ce lien<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Inscription<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez assister \u00e0 l\u2019AGE, veuillez contacter <a href=\"mailto:administration@acfo-acaf.com\">administration@acfo-acaf.com<\/a> pour obtenir le lien pour vous inscrire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez noter qu\u2019<strong>au cours de l\u2019AGE, les discussions ne pourront porter que sur la modification propos\u00e9e<\/strong>. Les membres de l\u2019ACFO-ACAF qui souhaitent discuter d\u2019autres sujets sont invit\u00e9s \u00e0 <a href=\"mailto:info@acfo-acaf.com\" data-type=\"mailto\" data-id=\"mailto:info@acfo-acaf.com\">communiquer avec nous<\/a> ou \u00e0 assister \u00e0 notre assembl\u00e9e g\u00e9n\u00e9rale annuelle, qui aura lieu le 30\u00a0octobre 2024.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Information pour le vote<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les membres de l\u2019ACFO-ACAF auront la possibilit\u00e9 de voter sur la modification du R\u00e8glement soit en personne, soit en ligne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Vote en personne<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les membres qui souhaitent remettre leur vote en personne pourront le faire au bureau de l\u2019ACFO\u2011ACAF (193&nbsp;chemin Richmond, Ottawa ON, K1Z 6W4)&nbsp;<strong>le 6 ao\u00fbt 2024, de 17&nbsp;h 00 \u00e0 19&nbsp;h 00 HE.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Vote en ligne<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les membres qui souhaitent voter en ligne peuvent le faire en utilisant le lien qui sera envoy\u00e9 par courriel le 17&nbsp;juillet 2024 \u00e0 12&nbsp;h 00 HE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La date limite pour voter \u00e9lectroniquement est<strong>&nbsp;le 6&nbsp;ao\u00fbt 2024 \u00e0 19&nbsp;h 00 HE.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les membres de l\u2019ACFO-ACAF qui ont l\u2019intention de voter en ligne sont invit\u00e9s \u00e0 v\u00e9rifier si leurs coordonn\u00e9es sont \u00e0 jour sur le portail des membres de l\u2019ACFO-ACAF. Pour ce faire, il suffit de suivre les instructions donn\u00e9es <a href=\"https:\/\/www.acfo-acaf.com\/wp-content\/uploads\/2024\/07\/2024-07-09-HowToUpdateYourInformation-FR.pdf\" data-type=\"link\" data-id=\"https:\/\/www.acfo-acaf.com\/wp-content\/uploads\/2024\/07\/2024-07-09-HowToUpdateYourInformation-FR.pdf\">sur cette page<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>R\u00e9sultats<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les r\u00e9sultats du vote sur la proposition de modification du R\u00e8glement seront communiqu\u00e9s aux membres de l\u2019ACFO-ACAF par courriel le 7 ao\u00fbt 2024, le jour m\u00eame o\u00f9 nous publierons l\u2019avis de convocation pr\u00e9liminaire \u00e0 notre AGA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Des questions?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez des questions au sujet de la prochaine AGE, veuillez envoyer un courriel \u00e0&nbsp;<a href=\"mailto:administration@acfo-acaf.com\">administration@acfo-acaf.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conform\u00e9ment \u00e0 l\u2019article 9.12.1 du R\u00e8glement, le Conseil d\u2019administration de l\u2019ACFO-ACAF a convoqu\u00e9 une assembl\u00e9e g\u00e9n\u00e9rale extraordinaire (AGE) qui aura [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-5681","post","type-post","status-publish","format-standard","hentry","category-mise-jour","group-ct-eav-fr","group-ct-fin-fr","group-ct-iau-fr","group-nav-canada-fl-fr"],"acf":{"categories":[38],"groups":[30,32,34,36],"canBeFeatured":false},"_links":{"self":[{"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/posts\/5681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/comments?post=5681"}],"version-history":[{"count":0,"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/posts\/5681\/revisions"}],"acf:term":[{"embeddable":true,"taxonomy":"group","href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/group\/36"},{"embeddable":true,"taxonomy":"group","href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/group\/34"},{"embeddable":true,"taxonomy":"group","href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/group\/32"},{"embeddable":true,"taxonomy":"group","href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/group\/30"},{"embeddable":true,"taxonomy":"category","href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/categories\/38"}],"wp:attachment":[{"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/media?parent=5681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/categories?post=5681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.acfo-acaf.com\/fr\/wp-json\/wp\/v2\/tags?post=5681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}